{"id":3020,"date":"2023-01-24T17:57:28","date_gmt":"2023-01-24T17:57:28","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/gb-mg\/"},"modified":"2026-05-13T15:38:30","modified_gmt":"2026-05-13T13:38:30","slug":"gb-mg","status":"publish","type":"product","link":"https:\/\/mail.cycling-originals.com\/pt\/retro-wielershirt\/gb-mg\/","title":{"rendered":"CAMISA DE CICLISMO GB-MG (c)-LATEXCO-BRICOBI-BIANCHI 1994"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3019,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-3020","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GB-MG (c)-LATEXCO-BRICOBI-BIANCHI  1994   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cycling-originals.com\/pt\/camisa-de-ciclismo-retro\/gb-mg\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GB-MG (c)-LATEXCO-BRICOBI-BIANCHI  1994   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cycling-originals.com\/pt\/camisa-de-ciclismo-retro\/gb-mg\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:38:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA43619.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/gb-mg\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/gb-mg\\\/\",\"name\":\"GB-MG (c)-LATEXCO-BRICOBI-BIANCHI 1994 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/gb-mg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/gb-mg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43619.jpg\",\"datePublished\":\"2023-01-24T17:57:28+00:00\",\"dateModified\":\"2026-05-13T13:38:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/gb-mg\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/gb-mg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/gb-mg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43619.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43619.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/gb-mg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GB-MG (c)-LATEXCO-BRICOBI-BIANCHI 1994 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GB-MG (c)-LATEXCO-BRICOBI-BIANCHI 1994 CAMISA DE CICLISMO - Ton Merckx Cycling Jerseys - Tour pelo mundo das camisas de ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cycling-originals.com\/pt\/camisa-de-ciclismo-retro\/gb-mg\/","og_locale":"pt_PT","og_type":"article","og_title":"GB-MG (c)-LATEXCO-BRICOBI-BIANCHI  1994   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.cycling-originals.com\/pt\/camisa-de-ciclismo-retro\/gb-mg\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:38:30+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA43619.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/gb-mg\/","url":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/gb-mg\/","name":"GB-MG (c)-LATEXCO-BRICOBI-BIANCHI 1994 CAMISA DE CICLISMO - Ton Merckx Cycling Jerseys - Tour pelo mundo das camisas de ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/gb-mg\/#primaryimage"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/gb-mg\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA43619.jpg","datePublished":"2023-01-24T17:57:28+00:00","dateModified":"2026-05-13T13:38:30+00:00","breadcrumb":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/gb-mg\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/gb-mg\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/gb-mg\/#primaryimage","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA43619.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA43619.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/gb-mg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"GB-MG (c)-LATEXCO-BRICOBI-BIANCHI 1994 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","description":"milhares de camisas de ciclismo originais - encomende a sua r\u00e9plica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Camisas de ciclismo Ton Merckx - Tour pelo mundo das camisas de ciclismo","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cycling-originals.com\/pt\/wp-json\/wp\/v2\/product\/3020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cycling-originals.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cycling-originals.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/pt\/wp-json\/wp\/v2\/media\/3019"}],"wp:attachment":[{"href":"https:\/\/mail.cycling-originals.com\/pt\/wp-json\/wp\/v2\/media?parent=3020"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/pt\/wp-json\/wp\/v2\/product_brand?post=3020"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/pt\/wp-json\/wp\/v2\/product_cat?post=3020"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/pt\/wp-json\/wp\/v2\/product_tag?post=3020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}