{"id":3110,"date":"2023-01-24T17:58:34","date_gmt":"2023-01-24T17:58:34","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/mapei-gb\/"},"modified":"2026-05-13T15:38:26","modified_gmt":"2026-05-13T13:38:26","slug":"mapei-gb","status":"publish","type":"product","link":"https:\/\/mail.cycling-originals.com\/it\/retro-wielershirt\/mapei-gb\/","title":{"rendered":"MAGLIA CICLISMO MAPEI (c)-GB-LATEXCO 1995"},"content":{"rendered":"<p>Dopo la fusione con la CLAS-CAJASTUR nel 1994, nel 1995 segu\u00ec la fusione con la squadra belga\/italiana GB-MG.<\/p>\n<p>Ci\u00f2 significa che anche Patrick Lefevere si unisce al team come team leader (e successivamente Team Manager), il che non danneggia il team MAPEI.<\/p>\n<p>Diventano la squadra migliore delle Classiche Fiamminghi e i corridori MAPEI colorano anche la corsa della Parigi-Roubaix. Nel 1995 la squadra MAPEI ha vinto ben 82 gare, tra cui: Omloop het Volk, Parigi-Roubaix, Giro delle Fiandre, Campionato di Zurigo, Campionato del Mondo Cronometro, Giro d&#039;Italia, Parigi-Bruxelles e la classifica finale della Coppa del Mondo. , sia come squadra che individualmente (Johan Museeuw).<\/p>","protected":false},"excerpt":{"rendered":"<p>Na de fusie met CLAS-CAJASTUR in 1994, volgt in 1995 een fusie met de Belgisch\/Italiaanse ploeg GB-MG. Daarmee komt ook Patrick Lefevere als ploegleider (en later Teammanager) bij de ploeg, dit legt de MAPEI ploeg geen windeieren. Men wordt de beste ploeg in de Vlaamse Klassiekers en ook in Parijs-Roubaix kleuren de MAPEI renners de [&hellip;]<\/p>\n","protected":false},"featured_media":3109,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-3110","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MAPEI (c)-GB-LATEXCO  1995  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/mapei-gb\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MAPEI (c)-GB-LATEXCO  1995  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"Na de fusie met CLAS-CAJASTUR in 1994, volgt in 1995 een fusie met de Belgisch\/Italiaanse ploeg GB-MG. Daarmee komt ook Patrick Lefevere als ploegleider (en later Teammanager) bij de ploeg, dit legt de MAPEI ploeg geen windeieren. Men wordt de beste ploeg in de Vlaamse Klassiekers en ook in Parijs-Roubaix kleuren de MAPEI renners de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/mapei-gb\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:38:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA44887.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/ja\\\/retro-wielershirt\\\/mapei-gb\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/ja\\\/retro-wielershirt\\\/mapei-gb\\\/\",\"name\":\"MAPEI (c)-GB-LATEXCO 1995 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/ja\\\/retro-wielershirt\\\/mapei-gb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/ja\\\/retro-wielershirt\\\/mapei-gb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA44887.jpg\",\"datePublished\":\"2023-01-24T17:58:34+00:00\",\"dateModified\":\"2026-05-13T13:38:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/ja\\\/retro-wielershirt\\\/mapei-gb\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cycling-originals.com\\\/ja\\\/retro-wielershirt\\\/mapei-gb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/ja\\\/retro-wielershirt\\\/mapei-gb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA44887.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA44887.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/ja\\\/retro-wielershirt\\\/mapei-gb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MAPEI (c)-GB-LATEXCO 1995 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAGLIA CICLISMO MAPEI (c)-GB-LATEXCO 1995 - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/mapei-gb\/","og_locale":"it_IT","og_type":"article","og_title":"MAPEI (c)-GB-LATEXCO  1995  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"Na de fusie met CLAS-CAJASTUR in 1994, volgt in 1995 een fusie met de Belgisch\/Italiaanse ploeg GB-MG. Daarmee komt ook Patrick Lefevere als ploegleider (en later Teammanager) bij de ploeg, dit legt de MAPEI ploeg geen windeieren. Men wordt de beste ploeg in de Vlaamse Klassiekers en ook in Parijs-Roubaix kleuren de MAPEI renners de [&hellip;]","og_url":"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/mapei-gb\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:38:26+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA44887.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cycling-originals.com\/ja\/retro-wielershirt\/mapei-gb\/","url":"https:\/\/mail.cycling-originals.com\/ja\/retro-wielershirt\/mapei-gb\/","name":"MAGLIA CICLISMO MAPEI (c)-GB-LATEXCO 1995 - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cycling-originals.com\/ja\/retro-wielershirt\/mapei-gb\/#primaryimage"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/ja\/retro-wielershirt\/mapei-gb\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA44887.jpg","datePublished":"2023-01-24T17:58:34+00:00","dateModified":"2026-05-13T13:38:26+00:00","breadcrumb":{"@id":"https:\/\/mail.cycling-originals.com\/ja\/retro-wielershirt\/mapei-gb\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cycling-originals.com\/ja\/retro-wielershirt\/mapei-gb\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.cycling-originals.com\/ja\/retro-wielershirt\/mapei-gb\/#primaryimage","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA44887.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/SSA44887.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cycling-originals.com\/ja\/retro-wielershirt\/mapei-gb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"MAPEI (c)-GB-LATEXCO 1995 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product\/3110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/media\/3109"}],"wp:attachment":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/media?parent=3110"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product_brand?post=3110"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product_cat?post=3110"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product_tag?post=3110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}