{"id":29446,"date":"2024-06-05T21:36:02","date_gmt":"2024-06-05T19:36:02","guid":{"rendered":"https:\/\/mail.cycling-originals.com\/?post_type=product&#038;p=29446"},"modified":"2026-08-20T14:28:46","modified_gmt":"2026-08-20T12:28:46","slug":"classifica-generale-3","status":"publish","type":"product","link":"https:\/\/mail.cycling-originals.com\/it\/retro-wielershirt\/mars-flandria-1971\/","title":{"rendered":"MAGLIA DA CICLISMO MARS-FLANDRIA 1971"},"content":{"rendered":"<p>MARTE-FLANDRIA 1971<\/p>","protected":false},"excerpt":{"rendered":"<p>MARTE-FLANDRIA 1971<\/p>","protected":false},"featured_media":29456,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-29446","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MARS-FLANDRIA  1971                                   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/classifica-generale-3\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MARS-FLANDRIA  1971                                   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"MARS-FLANDRIA 1971\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/classifica-generale-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-20T12:28:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/06\/IMG_2068-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-3\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-3\\\/\",\"name\":\"MARS-FLANDRIA 1971 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_2068-scaled.jpg\",\"datePublished\":\"2024-06-05T19:36:02+00:00\",\"dateModified\":\"2026-08-20T12:28:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-3\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_2068-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_2068-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"MARS-FLANDRIA 1971\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/retro-radtrikots\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MARS-FLANDRIA 1971 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tonmerckxwielershirts.nl\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAGLIA DA CICLISMO MARS-FLANDRIA 1971 - Maglie da ciclismo Ton Merckx - Viaggio nel mondo delle maglie da ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/classifica-generale-3\/","og_locale":"it_IT","og_type":"article","og_title":"MARS-FLANDRIA  1971                                   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"MARS-FLANDRIA 1971","og_url":"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/classifica-generale-3\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-08-20T12:28:46+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/06\/IMG_2068-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-3\/","url":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-3\/","name":"MAGLIA DA CICLISMO MARS-FLANDRIA 1971 - Maglie da ciclismo Ton Merckx - Viaggio nel mondo delle maglie da ciclismo","isPartOf":{"@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-3\/#primaryimage"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-3\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/06\/IMG_2068-scaled.jpg","datePublished":"2024-06-05T19:36:02+00:00","dateModified":"2026-08-20T12:28:46+00:00","breadcrumb":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-3\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-3\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-3\/#primaryimage","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/06\/IMG_2068-scaled.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/06\/IMG_2068-scaled.jpg","width":1920,"height":2560,"caption":"MARS-FLANDRIA 1971"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tonmerckxwielershirts.nl\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/www.tonmerckxwielershirts.nl\/de\/retro-radtrikots\/"},{"@type":"ListItem","position":3,"name":"MARS-FLANDRIA 1971 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#website","url":"https:\/\/www.tonmerckxwielershirts.nl\/de\/","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tonmerckxwielershirts.nl\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#organization","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","url":"https:\/\/www.tonmerckxwielershirts.nl\/de\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/www.tonmerckxwielershirts.nl\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product\/29446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/media\/29456"}],"wp:attachment":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/media?parent=29446"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product_brand?post=29446"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product_cat?post=29446"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product_tag?post=29446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}