{"id":27947,"date":"2023-09-29T13:30:06","date_gmt":"2023-09-29T11:30:06","guid":{"rendered":"https:\/\/mail.cycling-originals.com\/?post_type=product&#038;p=27947"},"modified":"2026-05-13T15:36:56","modified_gmt":"2026-05-13T13:36:56","slug":"aa-bevande-leontien-nl-27","status":"publish","type":"product","link":"https:\/\/mail.cycling-originals.com\/it\/retro-wielershirt\/wielershirt-human-powered-health\/","title":{"rendered":"MAGLIA DA CICLISMO HUMAN POWERED HEALTH 2022"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":27957,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-27947","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HUMAN POWERED HEALTH  2022  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HUMAN POWERED HEALTH  2022  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:36:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ton.connectingminds.net\/wp-content\/uploads\/2023\/09\/IMG_1554.png\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/retro-wielershirt\\\/wielershirt-human-powered-health\\\/\",\"url\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/retro-wielershirt\\\/wielershirt-human-powered-health\\\/\",\"name\":\"HUMAN POWERED HEALTH 2022 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/retro-wielershirt\\\/wielershirt-human-powered-health\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/retro-wielershirt\\\/wielershirt-human-powered-health\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_1554.png\",\"datePublished\":\"2023-09-29T11:30:06+00:00\",\"dateModified\":\"2026-05-13T13:36:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/retro-wielershirt\\\/wielershirt-human-powered-health\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ton.connectingminds.net\\\/retro-wielershirt\\\/wielershirt-human-powered-health\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/retro-wielershirt\\\/wielershirt-human-powered-health\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_1554.png\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/IMG_1554.png\",\"width\":240,\"height\":320},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/retro-wielershirt\\\/wielershirt-human-powered-health\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"HUMAN POWERED HEALTH 2022 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAGLIA DA CICLISMO HUMAN POWERED HEALTH 2022 - Maglie da ciclismo Ton Merckx - Viaggio nel mondo delle maglie da ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/","og_locale":"it_IT","og_type":"article","og_title":"HUMAN POWERED HEALTH  2022  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:36:56+00:00","og_image":[{"width":240,"height":320,"url":"https:\/\/www.ton.connectingminds.net\/wp-content\/uploads\/2023\/09\/IMG_1554.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/","url":"https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/","name":"MAGLIA DA CICLISMO HUMAN POWERED HEALTH 2022 - Maglie da ciclismo Ton Merckx - Viaggio nel mondo delle maglie da ciclismo","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/#primaryimage"},"image":{"@id":"https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/09\/IMG_1554.png","datePublished":"2023-09-29T11:30:06+00:00","dateModified":"2026-05-13T13:36:56+00:00","breadcrumb":{"@id":"https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/#primaryimage","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/09\/IMG_1554.png","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/09\/IMG_1554.png","width":240,"height":320},{"@type":"BreadcrumbList","@id":"https:\/\/www.ton.connectingminds.net\/retro-wielershirt\/wielershirt-human-powered-health\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"HUMAN POWERED HEALTH 2022 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product\/27947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/media\/27957"}],"wp:attachment":[{"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/media?parent=27947"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product_brand?post=27947"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product_cat?post=27947"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/it\/wp-json\/wp\/v2\/product_tag?post=27947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}