{"id":885,"date":"2023-01-24T17:32:37","date_gmt":"2023-01-24T17:32:37","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/alpecin-fenix-tour-de-france-1e-etappe\/"},"modified":"2026-07-06T08:50:30","modified_gmt":"2026-07-06T06:50:30","slug":"alpecin-fenix-tour-de-france-1ere-etape","status":"publish","type":"product","link":"https:\/\/mail.cycling-originals.com\/fr\/retro-wielershirt\/alpecin-fenix-tour-de-france-1e-etappe\/","title":{"rendered":"ALPECIN (b)-FENIX  TOUR DE FRANCE  1e ETAPPE  2021                           WIELERSHIRT"},"content":{"rendered":"<p>ALPECIN-FENIX TOUR DE FRANCE 1e ETAPPE 2021<\/p>\n<p>Maillot sp\u00e9cial pour la premi\u00e8re \u00e9tape du Tour de France 2021.<\/p>\n<p>Destin\u00e9 \u00e0 rendre hommage \u00e0 l&#039;\u00e9quipe MERCIER de Raymond Poulidor des ann\u00e9es 1960, Raymond Poulidor est le grand-p\u00e8re du leader de l&#039;\u00e9quipe ALPECIN Matthieu van der Poel.<\/p>","protected":false},"excerpt":{"rendered":"<p>ALPECIN-FENIX TOUR DE FRANCE 1e ETAPPE 2021 Speciaal shirt voor de eerste etappe van de Tour de France 2021. Bedoeld als eerbetoon aan Raymond Poulidors MERCIER ploeg uit de jaren 60, Raymond Poulidor is de opa van de kopman van de ALPECIN ploeg Matthieu van der Poel<\/p>","protected":false},"featured_media":189763,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-885","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALPECIN (b)-FENIX TOUR DE FRANCE 1e ETAPPE 2021              WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cycling-originals.com\/fr\/maillot-de-cyclisme-retro\/alpecin-fenix-tour-de-france-1ere-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALPECIN (b)-FENIX TOUR DE FRANCE 1e ETAPPE 2021              WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"ALPECIN-FENIX TOUR DE FRANCE 1e ETAPPE 2021 Speciaal shirt voor de eerste etappe van de Tour de France 2021. Bedoeld als eerbetoon aan Raymond Poulidors MERCIER ploeg uit de jaren 60, Raymond Poulidor is de opa van de kopman van de ALPECIN ploeg Matthieu van der Poel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cycling-originals.com\/fr\/maillot-de-cyclisme-retro\/alpecin-fenix-tour-de-france-1ere-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T06:50:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/003-33-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/it\\\/maglia-da-ciclismo-retro\\\/alpecin-fenix-tour-de-france-1a-tappa\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/it\\\/maglia-da-ciclismo-retro\\\/alpecin-fenix-tour-de-france-1a-tappa\\\/\",\"name\":\"ALPECIN (b)-FENIX TOUR DE FRANCE 1e ETAPPE 2021 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/it\\\/maglia-da-ciclismo-retro\\\/alpecin-fenix-tour-de-france-1a-tappa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/it\\\/maglia-da-ciclismo-retro\\\/alpecin-fenix-tour-de-france-1a-tappa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/003-33-scaled.jpg\",\"datePublished\":\"2023-01-24T17:32:37+00:00\",\"dateModified\":\"2026-07-06T06:50:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/it\\\/maglia-da-ciclismo-retro\\\/alpecin-fenix-tour-de-france-1a-tappa\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cycling-originals.com\\\/it\\\/maglia-da-ciclismo-retro\\\/alpecin-fenix-tour-de-france-1a-tappa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/it\\\/maglia-da-ciclismo-retro\\\/alpecin-fenix-tour-de-france-1a-tappa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/003-33-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/003-33-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"ALPECIN-FENIX TOUR DE FRANCE 1e ETAPPE 2021\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/it\\\/maglia-da-ciclismo-retro\\\/alpecin-fenix-tour-de-france-1a-tappa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ALPECIN (b)-FENIX TOUR DE FRANCE 1e ETAPPE 2021 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALPECIN (b)-FENIX TOUR DE FRANCE 1e ETAPPE 2021              WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cycling-originals.com\/fr\/maillot-de-cyclisme-retro\/alpecin-fenix-tour-de-france-1ere-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"ALPECIN (b)-FENIX TOUR DE FRANCE 1e ETAPPE 2021              WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"ALPECIN-FENIX TOUR DE FRANCE 1e ETAPPE 2021 Speciaal shirt voor de eerste etappe van de Tour de France 2021. Bedoeld als eerbetoon aan Raymond Poulidors MERCIER ploeg uit de jaren 60, Raymond Poulidor is de opa van de kopman van de ALPECIN ploeg Matthieu van der Poel","og_url":"https:\/\/mail.cycling-originals.com\/fr\/maillot-de-cyclisme-retro\/alpecin-fenix-tour-de-france-1ere-etape\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-07-06T06:50:30+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/003-33-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/alpecin-fenix-tour-de-france-1a-tappa\/","url":"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/alpecin-fenix-tour-de-france-1a-tappa\/","name":"ALPECIN (b)-FENIX TOUR DE FRANCE 1e ETAPPE 2021 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/alpecin-fenix-tour-de-france-1a-tappa\/#primaryimage"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/alpecin-fenix-tour-de-france-1a-tappa\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/003-33-scaled.jpg","datePublished":"2023-01-24T17:32:37+00:00","dateModified":"2026-07-06T06:50:30+00:00","breadcrumb":{"@id":"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/alpecin-fenix-tour-de-france-1a-tappa\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/alpecin-fenix-tour-de-france-1a-tappa\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/alpecin-fenix-tour-de-france-1a-tappa\/#primaryimage","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/003-33-scaled.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/003-33-scaled.jpg","width":1920,"height":2560,"caption":"ALPECIN-FENIX TOUR DE FRANCE 1e ETAPPE 2021"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cycling-originals.com\/it\/maglia-da-ciclismo-retro\/alpecin-fenix-tour-de-france-1a-tappa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"ALPECIN (b)-FENIX TOUR DE FRANCE 1e ETAPPE 2021 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Chemises de cyclisme Ton Merckx - Tour \u00e0 travers le monde des chemises de cyclisme","description":"des milliers de maillots de cyclisme originaux - commandez votre r\u00e9plique !","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Chemises de cyclisme Ton Merckx - Tour \u00e0 travers le monde des chemises de cyclisme","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cycling-originals.com\/fr\/wp-json\/wp\/v2\/product\/885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cycling-originals.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cycling-originals.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/fr\/wp-json\/wp\/v2\/media\/189763"}],"wp:attachment":[{"href":"https:\/\/mail.cycling-originals.com\/fr\/wp-json\/wp\/v2\/media?parent=885"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/fr\/wp-json\/wp\/v2\/product_brand?post=885"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/fr\/wp-json\/wp\/v2\/product_cat?post=885"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/fr\/wp-json\/wp\/v2\/product_tag?post=885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}