{"id":30569,"date":"2024-06-10T23:04:13","date_gmt":"2024-06-10T21:04:13","guid":{"rendered":"https:\/\/mail.cycling-originals.com\/?post_type=product&#038;p=30569"},"modified":"2026-05-13T15:36:39","modified_gmt":"2026-05-13T13:36:39","slug":"ranking-general-29","status":"publish","type":"product","link":"https:\/\/mail.cycling-originals.com\/es\/retro-wielershirt\/somerset-mall-1997\/","title":{"rendered":"SOMERSET MALL (b) 1997 CAMISETA DE CICLISMO"},"content":{"rendered":"<p>Centro Comercial Somerset 1997<\/p>\n<p>Equipo ocasional de la gira de Boland Bank o Giro Del Capo.<\/p>","protected":false},"excerpt":{"rendered":"<p>SOMERSET MALL 1997 Equipo ocasional de la gira de Boland Bank por el Giro Del Capo<\/p>","protected":false},"featured_media":30579,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-30569","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SOMERSET MALL (b) 1997  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cycling-originals.com\/es\/maillot-ciclista-retro\/ranking-general-29\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOMERSET MALL (b) 1997  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"SOMERSET MALL 1997 Gelegenheidsploeg uit de Boland Bank tour of Giro Del Capo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cycling-originals.com\/es\/maillot-ciclista-retro\/ranking-general-29\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:36:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/06\/IMG_2715-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-28\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-28\\\/\",\"name\":\"SOMERSET MALL (b) 1997 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-28\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-28\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_2715-scaled.jpg\",\"datePublished\":\"2024-06-10T21:04:13+00:00\",\"dateModified\":\"2026-05-13T13:36:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-28\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-28\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-28\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_2715-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IMG_2715-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"SOMERSET MALL 1997\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/de\\\/retro-radtrikot\\\/allgemeines-ranking-28\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/tonmerckxwielershirts.nl\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SOMERSET MALL (b) 1997 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#website\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAMISETA DE CICLISMO SOMERSET MALL (b) 1997 - Maillots de ciclismo Ton Merckx - Recorrido por el mundo de los maillots de ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cycling-originals.com\/es\/maillot-ciclista-retro\/ranking-general-29\/","og_locale":"es_ES","og_type":"article","og_title":"SOMERSET MALL (b) 1997  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"SOMERSET MALL 1997 Gelegenheidsploeg uit de Boland Bank tour of Giro Del Capo","og_url":"https:\/\/mail.cycling-originals.com\/es\/maillot-ciclista-retro\/ranking-general-29\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:36:39+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/06\/IMG_2715-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-28\/","url":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-28\/","name":"CAMISETA DE CICLISMO SOMERSET MALL (b) 1997 - Maillots de ciclismo Ton Merckx - Recorrido por el mundo de los maillots de ciclismo","isPartOf":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-28\/#primaryimage"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-28\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/06\/IMG_2715-scaled.jpg","datePublished":"2024-06-10T21:04:13+00:00","dateModified":"2026-05-13T13:36:39+00:00","breadcrumb":{"@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-28\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-28\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-28\/#primaryimage","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/06\/IMG_2715-scaled.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2024\/06\/IMG_2715-scaled.jpg","width":1920,"height":2560,"caption":"SOMERSET MALL 1997"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cycling-originals.com\/de\/retro-radtrikot\/allgemeines-ranking-28\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tonmerckxwielershirts.nl\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/tonmerckxwielershirts.nl\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"SOMERSET MALL (b) 1997 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.replica-cycling.com\/ja\/#website","url":"https:\/\/mail.replica-cycling.com\/ja\/","name":"Camisetas ciclistas Ton Merckx - Recorrido por el mundo de las camisetas ciclistas","description":"miles de maillots ciclistas originales - \u00a1pide tu r\u00e9plica!","publisher":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.replica-cycling.com\/ja\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mail.replica-cycling.com\/ja\/#organization","name":"Camisetas ciclistas Ton Merckx - Recorrido por el mundo de las camisetas ciclistas","url":"https:\/\/mail.replica-cycling.com\/ja\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cycling-originals.com\/es\/wp-json\/wp\/v2\/product\/30569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cycling-originals.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cycling-originals.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/es\/wp-json\/wp\/v2\/media\/30579"}],"wp:attachment":[{"href":"https:\/\/mail.cycling-originals.com\/es\/wp-json\/wp\/v2\/media?parent=30569"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/es\/wp-json\/wp\/v2\/product_brand?post=30569"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/es\/wp-json\/wp\/v2\/product_cat?post=30569"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/es\/wp-json\/wp\/v2\/product_tag?post=30569"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}