{"id":2832,"date":"2023-01-24T17:54:59","date_gmt":"2023-01-24T17:54:59","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/nationale-ploeg-4\/"},"modified":"2026-05-13T15:38:38","modified_gmt":"2026-05-13T13:38:38","slug":"nationalmannschaft-4","status":"publish","type":"product","link":"https:\/\/mail.cycling-originals.com\/de\/retro-wielershirt\/nationale-ploeg-4\/","title":{"rendered":"GRIECHISCHES FAHRRAD-NATIONALMANNSCHAFTS-HEMD"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2831,"template":"","meta":[],"product_brand":[],"product_cat":[1372],"product_tag":[],"class_list":["post-2832","product","type-product","status-publish","has-post-thumbnail","product_cat-nationale-teams","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GRIEKENLAND NATIONALE PLOEG                         WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GRIEKENLAND NATIONALE PLOEG                         WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:38:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_0893-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/pt\\\/retro-wielershirt\\\/nationale-ploeg-4\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/pt\\\/retro-wielershirt\\\/nationale-ploeg-4\\\/\",\"name\":\"GRIEKENLAND NATIONALE PLOEG WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/pt\\\/retro-wielershirt\\\/nationale-ploeg-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/pt\\\/retro-wielershirt\\\/nationale-ploeg-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_0893-scaled.jpg\",\"datePublished\":\"2023-01-24T17:54:59+00:00\",\"dateModified\":\"2026-05-13T13:38:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/pt\\\/retro-wielershirt\\\/nationale-ploeg-4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/pt\\\/retro-wielershirt\\\/nationale-ploeg-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/pt\\\/retro-wielershirt\\\/nationale-ploeg-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_0893-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_0893-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/pt\\\/retro-wielershirt\\\/nationale-ploeg-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GRIEKENLAND NATIONALE PLOEG WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cycling-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GRIECHISCHES FAHRRAD-NATIONALMANNSCHAFTS-HEMD - Ton Merckx Radtrikots - Tour durch die Welt der Radtrikots","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/","og_locale":"de_DE","og_type":"article","og_title":"GRIEKENLAND NATIONALE PLOEG                         WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:38:38+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_0893-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/","name":"GRIECHISCHES FAHRRAD-NATIONALMANNSCHAFTS-HEMD - Ton Merckx Radtrikots - Tour durch die Welt der Radtrikots","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/#primaryimage"},"image":{"@id":"https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/IMG_0893-scaled.jpg","datePublished":"2023-01-24T17:54:59+00:00","dateModified":"2026-05-13T13:38:38+00:00","breadcrumb":{"@id":"https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/#primaryimage","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/IMG_0893-scaled.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/01\/IMG_0893-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/mail.cyclingjerseys-originals.com\/pt\/retro-wielershirt\/nationale-ploeg-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"GRIEKENLAND NATIONALE PLOEG WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","description":"Tausende originale Radtrikots \u2013 bestellen Sie Ihr Replikat!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cycling-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cycling-originals.com\/de\/wp-json\/wp\/v2\/product\/2832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cycling-originals.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cycling-originals.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/de\/wp-json\/wp\/v2\/media\/2831"}],"wp:attachment":[{"href":"https:\/\/mail.cycling-originals.com\/de\/wp-json\/wp\/v2\/media?parent=2832"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/de\/wp-json\/wp\/v2\/product_brand?post=2832"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/de\/wp-json\/wp\/v2\/product_cat?post=2832"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cycling-originals.com\/de\/wp-json\/wp\/v2\/product_tag?post=2832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}